{"id":9273,"date":"2024-09-05T11:49:10","date_gmt":"2024-09-05T09:49:10","guid":{"rendered":"https:\/\/www.noidiqua.it\/Agliana\/?p=9273"},"modified":"2024-12-20T09:32:02","modified_gmt":"2024-12-20T08:32:02","slug":"museo-della-maglieria-al-maglificio-beby","status":"publish","type":"post","link":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/","title":{"rendered":"Museo della maglieria al Maglificio Beby"},"content":{"rendered":"<p><em>di Piera Salvi<\/em><\/p>\n<p><em>settembre 2024<\/em><\/p>\n<p><a href=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\" rel=\"wp-prettyPhoto[9273]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9274\" src=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\" alt=\"\" width=\"503\" height=\"330\" srcset=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png 503w, https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2-300x197.png 300w\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" \/><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\">Al <strong>Maglificio Beby<\/strong> circa un secolo di storia \u00e8 cristallizzata nel \u201c<strong>Piccolo museo della maglieria Aldo e Marcella Cangioli<\/strong>\u201d. I titolari, <strong>Fausto Reali Vannucci<\/strong> e la moglie <strong>Stefania Nerozzi<\/strong>, hanno cos\u00ec realizzato un sogno coltivato per anni. Fausto e Stefania stanno portando avanti una lunga tradizione di famiglia nella maglieria e hanno voluto fermare la memoria di un settore che ha dato grande impulso al territorio. Una volont\u00e0 che trova le radici nella loro formazione e passione per la storia: lui laureato in scienze politiche con tesi sulla storia contemporanea, lei ex insegnante di lettere che ha deciso di affiancare il marito nell\u2019attivit\u00e0 di famiglia. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Il Maglificio Beby venne fondato nel 1952 da <strong>Aldo Cangioli<\/strong> e <strong>Marcella Nardi<\/strong>, ma la storia risale agli anni Trenta, quando a iniziare l\u2019attivit\u00e0 di maglieria (con macchina a mano) fu Maria, la madre di Marcella. Poi ha proseguito Maria Claudia Cangioli, figlia di Aldo e Marcella. La stessa filosofia aziendale, pur con le indispensabili innovazioni, \u00e8 portata avanti da Fausto e Stefania ed \u00e8 gi\u00e0 pronta la quinta generazione con i loro figli Alessandro e Maria Giulia.<\/span><\/p>\n<p><a href=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-1.png\" rel=\"wp-prettyPhoto[9273]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9275\" src=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-1.png\" alt=\"\" width=\"499\" height=\"387\" srcset=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-1.png 499w, https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-1-300x233.png 300w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\">Per l\u2019inaugurazione, tra grandissime emozioni, \u00e8 entrato in funzione l\u2019altoparlante dal quale Aldo chiamava i suoi dipendenti, \u00e8 stato proiettato un video del 2013 con testimonianze di dipendenti e titolari, non solo sulla storia della ditta e le <strong>tecniche di lavorazione<\/strong>, ma sul rapporto umano tra i titolari e i dipendenti e tra i colleghi. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nel \u201cPiccolo museo\u201d in tre stanze \u00e8 cristallizzato circa un secolo di <strong>storia<\/strong> della maglieria. Ci sono vecchi testi sulla maglieria e documenti, macchine degli anni &#8217;50 e &#8217;60, altre di circa un secolo fa, alle quali lavorava la \u201c<strong>nonna Maria<\/strong>\u201d, c\u2019\u00e8 anche un antico telaio manuale in legno, che in passato era al terzo piano del palazzo comunale, poi trasferito in una scuola e ora prestato dal Comune al \u201cPiccolo museo\u201d. Una camiciola da donna ricorda le prime lavorazioni: fu tra i primi capi realizzati dal Maglificio Beby che inizi\u00f2 con la produzione di <strong>camiciole<\/strong>, canottiere e mutande di lana da uomo. Oggi \u00e8 specializzato nella produzione di alta qualit\u00e0 in <strong>cashmere<\/strong>. Anche in ditta convivono macchinari di moderna tecnologia e macchinari storici ancora funzionanti. E la sirena continua a scandire la fine del turno di lavoro.<\/span><\/p>\n<p><a href=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-3.png\" rel=\"wp-prettyPhoto[9273]\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9276\" src=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-3.png\" alt=\"\" width=\"498\" height=\"429\" srcset=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-3.png 498w, https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-3-300x258.png 300w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/a><\/p>\n<p class=\"p1\"><span class=\"s1\">Tante persone e molte autorit\u00e0 erano presenti all\u2019<strong>inaugurazione<\/strong>. Hanno tagliato il nastro i titolari del Maglificio Beby, Fausto Reali Vannucci e la moglie Stefania Nerozzi, con i loro figli Alessandro e Maria Giulia. Alle loro spalle i dipendenti e durante la cerimonia c\u2019\u00e8 stato un caloroso scambio di ringraziamenti. I titolari auspicano di ampliare il \u201cPiccolo museo\u201d. <i>\u00abLa produzione di maglieria\u00bb<\/i> evidenziano Fausto e Stefania <i>\u00abha rappresentato la fase di sviluppo sul nostro territorio dal dopoguerra in poi e ci \u00e8 sembrato giusto preservare la memoria. Tante persone credono in noi. Se siamo tanti a sognare, insieme si arriva all\u2019obiettivo\u00bb<\/i>. <\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>di Piera Salvi settembre 2024 Al Maglificio Beby circa un secolo di storia \u00e8 cristallizzata nel \u201cPiccolo museo della maglieria Aldo e Marcella Cangioli\u201d. I titolari, Fausto Reali Vannucci e la moglie Stefania Nerozzi, hanno cos\u00ec realizzato un sogno coltivato per anni. Fausto e Stefania stanno portando [&hellip;]<\/p>","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,3],"tags":[4388,4392,4393,395,4394,394,4389,4391,4386,4387,126,4390],"class_list":["post-9273","post","type-post","status-publish","format-standard","hentry","category-ag","category-arte-artigianato-qt","tag-aldo-cangioli","tag-camiciole","tag-cashmere","tag-fausto-reali-vannucci","tag-inaugurazione","tag-maglificio-beby","tag-marcella-nardi","tag-nonna-maria","tag-piccolo-museo-della-maglieria-aldo-e-marcella-cangioli","tag-stefania-nerozzi","tag-storia","tag-tecniche-di-lavorazione"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.\" \/>\n<meta property=\"og:description\" content=\"di Piera Salvi settembre 2024 Al Maglificio Beby circa un secolo di storia \u00e8 cristallizzata nel \u201cPiccolo museo della maglieria Aldo e Marcella Cangioli\u201d. I titolari, Fausto Reali Vannucci e la moglie Stefania Nerozzi, hanno cos\u00ec realizzato un sogno coltivato per anni. Fausto e Stefania stanno portando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/\" \/>\n<meta property=\"og:site_name\" content=\"Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/noidiqua.trimestrale\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-05T09:49:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T08:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\" \/>\n<meta name=\"author\" content=\"Piera Salvi\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Piera Salvi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/\",\"url\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/\",\"name\":\"Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.\",\"isPartOf\":{\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\",\"datePublished\":\"2024-09-05T09:49:10+00:00\",\"dateModified\":\"2024-12-20T08:32:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/bb7515c2330bb1137f247276096fa7dc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage\",\"url\":\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\",\"contentUrl\":\"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png\",\"width\":503,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.noidiqua.it\/Agliana\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Museo della maglieria al Maglificio Beby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/#website\",\"url\":\"https:\/\/www.noidiqua.it\/Agliana\/\",\"name\":\"Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.\",\"description\":\"Testata Giornalistica Quarrata Montale Agliana\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.noidiqua.it\/Agliana\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/bb7515c2330bb1137f247276096fa7dc\",\"name\":\"Piera Salvi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2f9b1fb6e13f3b3e63bde435d999a73be036e320f7a0f5f32f9ac21859d999cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2f9b1fb6e13f3b3e63bde435d999a73be036e320f7a0f5f32f9ac21859d999cd?s=96&d=mm&r=g\",\"caption\":\"Piera Salvi\"},\"url\":\"https:\/\/www.noidiqua.it\/Agliana\/author\/piera-salvi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/","og_locale":"it_IT","og_type":"article","og_title":"Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.","og_description":"di Piera Salvi settembre 2024 Al Maglificio Beby circa un secolo di storia \u00e8 cristallizzata nel \u201cPiccolo museo della maglieria Aldo e Marcella Cangioli\u201d. I titolari, Fausto Reali Vannucci e la moglie Stefania Nerozzi, hanno cos\u00ec realizzato un sogno coltivato per anni. Fausto e Stefania stanno portando [&hellip;]","og_url":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/","og_site_name":"Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.","article_publisher":"https:\/\/www.facebook.com\/noidiqua.trimestrale\/","article_published_time":"2024-09-05T09:49:10+00:00","article_modified_time":"2024-12-20T08:32:02+00:00","og_image":[{"url":"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png","type":"","width":"","height":""}],"author":"Piera Salvi","twitter_misc":{"Scritto da":"Piera Salvi","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/","url":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/","name":"Museo della maglieria al Maglificio Beby - Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.","isPartOf":{"@id":"https:\/\/www.noidiqua.it\/Agliana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage"},"image":{"@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage"},"thumbnailUrl":"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png","datePublished":"2024-09-05T09:49:10+00:00","dateModified":"2024-12-20T08:32:02+00:00","author":{"@id":"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/bb7515c2330bb1137f247276096fa7dc"},"breadcrumb":{"@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#primaryimage","url":"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png","contentUrl":"https:\/\/www.noidiqua.it\/Agliana\/wp-content\/uploads\/2024\/10\/Beby-2.png","width":503,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/www.noidiqua.it\/Agliana\/museo-della-maglieria-al-maglificio-beby\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noidiqua.it\/Agliana\/"},{"@type":"ListItem","position":2,"name":"Museo della maglieria al Maglificio Beby"}]},{"@type":"WebSite","@id":"https:\/\/www.noidiqua.it\/Agliana\/#website","url":"https:\/\/www.noidiqua.it\/Agliana\/","name":"Noi di Qua Testata giornalistica e di attualit\u00e0 di Agliana, Montale e Quarrata.","description":"Testata Giornalistica Quarrata Montale Agliana","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noidiqua.it\/Agliana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/bb7515c2330bb1137f247276096fa7dc","name":"Piera Salvi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.noidiqua.it\/Agliana\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2f9b1fb6e13f3b3e63bde435d999a73be036e320f7a0f5f32f9ac21859d999cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2f9b1fb6e13f3b3e63bde435d999a73be036e320f7a0f5f32f9ac21859d999cd?s=96&d=mm&r=g","caption":"Piera Salvi"},"url":"https:\/\/www.noidiqua.it\/Agliana\/author\/piera-salvi\/"}]}},"_links":{"self":[{"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/posts\/9273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/comments?post=9273"}],"version-history":[{"count":3,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/posts\/9273\/revisions"}],"predecessor-version":[{"id":9337,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/posts\/9273\/revisions\/9337"}],"wp:attachment":[{"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/media?parent=9273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/categories?post=9273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.noidiqua.it\/Agliana\/wp-json\/wp\/v2\/tags?post=9273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}